{"id":18517,"date":"2021-11-04T09:44:20","date_gmt":"2021-11-04T09:44:20","guid":{"rendered":"https:\/\/itecosrl.com\/?p=18517"},"modified":"2026-06-26T12:56:36","modified_gmt":"2026-06-26T12:56:36","slug":"truck-wash-garantisce-ai-tuoi-veicoli-un-lavaggio-immediato-e-di-qualita","status":"publish","type":"post","link":"https:\/\/itecosrl.com\/es\/truck-wash-garantisce-ai-tuoi-veicoli-un-lavaggio-immediato-e-di-qualita\/","title":{"rendered":"Truck Wash garantisce ai tuoi veicoli un lavaggio immediato e di qualit\u00e0"},"content":{"rendered":"<h3>Circuito di lavaggio<\/h3>\n<p>Il sistema di lavaggio Truck Wash \u00e8 fornito con spazzole antigraffio, per preservare la carrozzeria dei veicoli, e sistema di inclinazione, per pulire anche le parti frontali in pendenza tipica degli autobus.<\/p>\n<h3>Guida con timone sterzante<\/h3>\n<p>A differenza dei modelli Easy Wash con doppi comandi, Truck Wash ha il <strong>sistema di controllo<\/strong> e di <strong>guida posti nel manubrio dell\u2019impianto.<\/strong> L\u2019apparato di guida \u00e8 composto da un <strong>timone sterzante<\/strong> in grado di <strong>movimentare con facilit\u00e0 e sicurezza<\/strong> l\u2019impianto di lavaggio.<\/p>\n<p>In pi\u00f9 \u00e8 possibile avere su richiesta tre tipologie di guida:<\/p>\n  <div class=\"article-product-types single-blog-styles\">\n                <div class=\"article-product-types__item\">\n                  <div class=\"article-product-types__text\">\n            A terra          <\/div>\n        \n                  <div class=\"article-product-types__image\">\n            <picture><source srcset=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/Guida-a-terra-2.webp\" type=\"image\/webp\"><img loading=\"lazy\" src=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/Guida-a-terra-2.jpg\" alt=\"Guida-a-terra-2\"   width=\"200\" height=\"200\"  decoding=\"async\"  \/><\/picture>          <\/div>\n              <\/div>\n                <div class=\"article-product-types__item\">\n                  <div class=\"article-product-types__text\">\n            In piedi sul mezzo          <\/div>\n        \n                  <div class=\"article-product-types__image\">\n            <picture><source srcset=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/Guida-in-piedi-a-bordo.webp\" type=\"image\/webp\"><img loading=\"lazy\" src=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/Guida-in-piedi-a-bordo.jpg\" alt=\"Guida-in-piedi-a-bordo\"   width=\"200\" height=\"200\"  decoding=\"async\"  \/><\/picture>          <\/div>\n              <\/div>\n                <div class=\"article-product-types__item\">\n                  <div class=\"article-product-types__text\">\n            Seduto sul mezzo          <\/div>\n        \n                  <div class=\"article-product-types__image\">\n            <picture><source srcset=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/Guida-seduto-a-bordo.webp\" type=\"image\/webp\"><img loading=\"lazy\" src=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/Guida-seduto-a-bordo.jpg\" alt=\"Guida-seduto-a-bordo\"   width=\"200\" height=\"200\"  decoding=\"async\"  \/><\/picture>          <\/div>\n              <\/div>\n      <\/div>\n  \n<h3>Scopri il modello Truck Wash pi\u00f9 adatto a te!<\/h3>\n<p>Truck Wash \u00e8 disponibile in tre modelli:<\/p>\n  <div\n    class=\"article-product-grid-desc single-blog-styles article-product-grid-desc--count-3\"\n    style=\"--items-count: 3;\"\n  >\n                <div class=\"article-product-grid-desc__item\">\n                  <div class=\"article-product-grid-desc__image\">\n            <picture><source srcset=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/TW_D500-400x400-1.webp\" type=\"image\/webp\"><img loading=\"lazy\" src=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/TW_D500-400x400-1.jpg\" alt=\"TW_D500-400&#215;400\"   width=\"400\" height=\"400\"  decoding=\"async\"  \/><\/picture>          <\/div>\n        \n                  <div class=\"article-product-grid-desc__text\">\n            <p><strong>Truck Wash D500:<\/strong> alimentato a gasolio.<\/p>          <\/div>\n              <\/div>\n                <div class=\"article-product-grid-desc__item\">\n                  <div class=\"article-product-grid-desc__image\">\n            <picture><source srcset=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/TW_D500HP_side-400x400-1.webp\" type=\"image\/webp\"><img loading=\"lazy\" src=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/TW_D500HP_side-400x400-1.jpg\" alt=\"TW_D500HP_side-400&#215;400\"   width=\"400\" height=\"400\"  decoding=\"async\"  \/><\/picture>          <\/div>\n        \n                  <div class=\"article-product-grid-desc__text\">\n            <p><strong>Truck Wash D500 HP:<\/strong> con idropulitrice e avvolgitubo, alimentato a gasolio.<\/p>          <\/div>\n              <\/div>\n                <div class=\"article-product-grid-desc__item\">\n                  <div class=\"article-product-grid-desc__image\">\n            <picture><source srcset=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/TW_E500-400x400-1.webp\" type=\"image\/webp\"><img loading=\"lazy\" src=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/TW_E500-400x400-1.jpg\" alt=\"TW_E500-400&#215;400\"   width=\"400\" height=\"400\"  decoding=\"async\"  \/><\/picture>          <\/div>\n        \n                  <div class=\"article-product-grid-desc__text\">\n            <p><strong>Truck Wash E500:<\/strong> con motore elettrico alimentato a batteria.<\/p>          <\/div>\n              <\/div>\n      <\/div>","protected":false},"excerpt":{"rendered":"<p>Circuito di lavaggio Il sistema di lavaggio Truck Wash \u00e8 fornito con spazzole antigraffio, per preservare la carrozzeria dei veicoli, e sistema di inclinazione, per pulire anche le parti frontali in pendenza tipica degli autobus. Guida con timone sterzante A differenza dei modelli Easy Wash con doppi comandi, Truck Wash ha il sistema di controllo [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-18517","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"translation":{"provider":"WPGlobus","version":"2.10.10","language":"es","enabled_languages":["it","en","fr","es"],"languages":{"it":{"title":true,"content":true,"excerpt":false},"en":{"title":true,"content":true,"excerpt":false},"fr":{"title":false,"content":false,"excerpt":false},"es":{"title":false,"content":false,"excerpt":false}}},"acf":[],"_links":{"self":[{"href":"https:\/\/itecosrl.com\/es\/wp-json\/wp\/v2\/posts\/18517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/itecosrl.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/itecosrl.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/itecosrl.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/itecosrl.com\/es\/wp-json\/wp\/v2\/comments?post=18517"}],"version-history":[{"count":3,"href":"https:\/\/itecosrl.com\/es\/wp-json\/wp\/v2\/posts\/18517\/revisions"}],"predecessor-version":[{"id":18521,"href":"https:\/\/itecosrl.com\/es\/wp-json\/wp\/v2\/posts\/18517\/revisions\/18521"}],"wp:attachment":[{"href":"https:\/\/itecosrl.com\/es\/wp-json\/wp\/v2\/media?parent=18517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/itecosrl.com\/es\/wp-json\/wp\/v2\/categories?post=18517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/itecosrl.com\/es\/wp-json\/wp\/v2\/tags?post=18517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}