{"id":18560,"date":"2021-10-14T10:40:52","date_gmt":"2021-10-14T10:40:52","guid":{"rendered":"https:\/\/itecosrl.com\/?p=18560"},"modified":"2026-05-12T10:13:21","modified_gmt":"2026-05-12T10:13:21","slug":"full-wash-monospazzola-completa-di-tutti-gli-optionals-di-lavaggio","status":"publish","type":"post","link":"https:\/\/itecosrl.com\/es\/full-wash-monospazzola-completa-di-tutti-gli-optionals-di-lavaggio\/","title":{"rendered":"Full Wash: monospazzola completa di tutti gli optionals di lavaggio"},"content":{"rendered":"<div\n    class=\"article-images-grid article-images-grid--count-2\"\n    style=\"--items-count: 2;\"\n  >\n                        <div class=\"article-images-grid__item\">\n          <picture><source srcset=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/Full-Wash-bus-1-1024x576-1.webp\" type=\"image\/webp\"><img loading=\"lazy\" src=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/Full-Wash-bus-1-1024x576-1.jpg\" alt=\"Full-Wash-bus-1-1024&#215;576\"   width=\"1024\" height=\"576\"  decoding=\"async\"  \/><\/picture>        <\/div>\n                              <div class=\"article-images-grid__item\">\n          <picture><source srcset=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/Full-Wash-Camion-1-1024x576-1.webp\" type=\"image\/webp\"><img loading=\"lazy\" src=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/Full-Wash-Camion-1-1024x576-1.jpg\" alt=\"Full-Wash-Camion-1-1024&#215;576\"   width=\"1024\" height=\"576\"  decoding=\"async\"  \/><\/picture>        <\/div>\n            <\/div>\n  \n<p>L\u2019impianto <strong>Full Wash<\/strong> \u00e8 il <strong>modello pi\u00f9 performante tra i nostri monospazzola,<\/strong> grazie al suo motore bicilindrico 18 hp e pompa di lavaggio ad alta pressione \u00e8 in grado di offrire una pulizia professionale. Tra le dotazioni di serie:<\/p>\n  <div\n    class=\"article-image-text-grid single-blog-styles article-image-text-grid--count-4\"\n    style=\"--items-count: 4;\"\n  >\n                <div class=\"article-image-text-grid__item\">\n                  <div class=\"article-image-text-grid__image\">\n            <picture><source srcset=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/FW_back_DX-300x300-1.webp\" type=\"image\/webp\"><img loading=\"lazy\" src=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/FW_back_DX-300x300-1.jpg\" alt=\"FW_back_DX-300&#215;300\"   width=\"300\" height=\"300\"  decoding=\"async\"  \/><\/picture>          <\/div>\n        \n                  <div class=\"article-image-text-grid__text\">\n            <p><strong>Spazzola inclinabile<\/strong> di 20\u00b0\u00e8 in grado di pulire l\u2019intera carrozzeria dei veicoli.<\/p>          <\/div>\n              <\/div>\n                <div class=\"article-image-text-grid__item\">\n                  <div class=\"article-image-text-grid__image\">\n            <picture><source srcset=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/Chassis-monospazzola-bus-300x300-1.webp\" type=\"image\/webp\"><img loading=\"lazy\" src=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/Chassis-monospazzola-bus-300x300-1.jpg\" alt=\"Chassis-monospazzola-bus-300&#215;300\"   width=\"300\" height=\"300\"  decoding=\"async\"  \/><\/picture>          <\/div>\n        \n                  <div class=\"article-image-text-grid__text\">\n            <p><strong>Lavaggio sottoscocca laterale.<\/strong> Barra ad alta pressione con ugelli a lama per il lavaggio del sottoscocca<\/p>          <\/div>\n              <\/div>\n                <div class=\"article-image-text-grid__item\">\n                  <div class=\"article-image-text-grid__image\">\n            <picture><source srcset=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/FW_lancia-HP_3q-300x300-1.webp\" type=\"image\/webp\"><img loading=\"lazy\" src=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/FW_lancia-HP_3q-300x300-1.jpg\" alt=\"FW_lancia-HP_3q-300&#215;300\"   width=\"300\" height=\"300\"  decoding=\"async\"  \/><\/picture>          <\/div>\n        \n                  <div class=\"article-image-text-grid__text\">\n            <p><strong>Idropulitrice ad alta pressione con avvolgi tubo.<\/strong> Utile per raggiungere quei punti pi\u00f9 interni e nascosti come parafanghi, telai e sottoscocca.<\/p>          <\/div>\n              <\/div>\n                <div class=\"article-image-text-grid__item\">\n                  <div class=\"article-image-text-grid__image\">\n            <picture><source srcset=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/Fullwash_lancia_tetto-300x300-1.webp\" type=\"image\/webp\"><img loading=\"lazy\" src=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/Fullwash_lancia_tetto-300x300-1.jpg\" alt=\"Fullwash_lancia_tetto-300&#215;300\"   width=\"300\" height=\"300\"  decoding=\"async\"  \/><\/picture>          <\/div>\n        \n                  <div class=\"article-image-text-grid__text\">\n            <p><strong>Barra lava tetto ad alta pressione.<\/strong> Garantisce anche il lavaggio dei tetti dei veicoli solitamente trascurati dai normali sistemi di lavaggio monospazzola.<\/p>          <\/div>\n              <\/div>\n      <\/div>\n  \n<p><iframe loading=\"lazy\" title=\"Full Wash\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/x7-d-0WN7yA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>","protected":false},"excerpt":{"rendered":"<p>L\u2019impianto Full Wash \u00e8 il modello pi\u00f9 performante tra i nostri monospazzola, grazie al suo motore bicilindrico 18 hp e pompa di lavaggio ad alta pressione \u00e8 in grado di offrire una pulizia professionale. Tra le dotazioni di serie:<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-18560","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"translation":{"provider":"WPGlobus","version":"2.10.10","language":"es","enabled_languages":["it","en","fr","es"],"languages":{"it":{"title":true,"content":true,"excerpt":false},"en":{"title":true,"content":true,"excerpt":false},"fr":{"title":false,"content":false,"excerpt":false},"es":{"title":false,"content":false,"excerpt":false}}},"acf":[],"_links":{"self":[{"href":"https:\/\/itecosrl.com\/es\/wp-json\/wp\/v2\/posts\/18560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/itecosrl.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/itecosrl.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/itecosrl.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/itecosrl.com\/es\/wp-json\/wp\/v2\/comments?post=18560"}],"version-history":[{"count":3,"href":"https:\/\/itecosrl.com\/es\/wp-json\/wp\/v2\/posts\/18560\/revisions"}],"predecessor-version":[{"id":18571,"href":"https:\/\/itecosrl.com\/es\/wp-json\/wp\/v2\/posts\/18560\/revisions\/18571"}],"wp:attachment":[{"href":"https:\/\/itecosrl.com\/es\/wp-json\/wp\/v2\/media?parent=18560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/itecosrl.com\/es\/wp-json\/wp\/v2\/categories?post=18560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/itecosrl.com\/es\/wp-json\/wp\/v2\/tags?post=18560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}