{"id":18588,"date":"2021-10-07T11:08:32","date_gmt":"2021-10-07T11:08:32","guid":{"rendered":"https:\/\/itecosrl.com\/?p=18588"},"modified":"2026-05-12T10:13:23","modified_gmt":"2026-05-12T10:13:23","slug":"easy-wash-50-e-lavaggio-veicoli-completo-con-equipaggiamento-standard","status":"publish","type":"post","link":"https:\/\/itecosrl.com\/fr\/easy-wash-50-e-lavaggio-veicoli-completo-con-equipaggiamento-standard\/","title":{"rendered":"Easy Wash 50 E: lavaggio veicoli completo con equipaggiamento standard"},"content":{"rendered":"<p><strong>Easy Wash 50 E<\/strong> \u00e8 un sistema di lavaggio monospazzola progettato per offrire una pulizia professionale, veloce ed economica per ogni modello di veicolo da trasporto commerciale o pubblico.<\/p>\n  <div\n    class=\"article-images-grid article-images-grid--count-2\"\n    style=\"--items-count: 2;\"\n  >\n                        <div class=\"article-images-grid__item\">\n          <picture><source srcset=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/1008_Bus-Easy-Wash-50E-1024x576-1.webp\" type=\"image\/webp\"><img loading=\"lazy\" src=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/1008_Bus-Easy-Wash-50E-1024x576-1.jpg\" alt=\"1008_Bus-Easy-Wash-50E-1024&#215;576\"   width=\"1024\" height=\"576\"  decoding=\"async\"  \/><\/picture>        <\/div>\n                              <div class=\"article-images-grid__item\">\n          <picture><source srcset=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/1008_Camion-Easy-Wash-50E-1024x576-1.webp\" type=\"image\/webp\"><img loading=\"lazy\" src=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/1008_Camion-Easy-Wash-50E-1024x576-1.jpg\" alt=\"1008_Camion-Easy-Wash-50E-1024&#215;576\"   width=\"1024\" height=\"576\"  decoding=\"async\"  \/><\/picture>        <\/div>\n            <\/div>\n  \n  <div\n    class=\"article-images-grid article-images-grid--count-3\"\n    style=\"--items-count: 3;\"\n  >\n                        <div class=\"article-images-grid__item\">\n          <picture><source srcset=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/EW_front.webp\" type=\"image\/webp\"><img loading=\"lazy\" src=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/EW_front.jpg\" alt=\"EW_front\"   width=\"1000\" height=\"1000\"  decoding=\"async\"  \/><\/picture>        <\/div>\n                              <div class=\"article-images-grid__item\">\n          <picture><source srcset=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/EW_3q.webp\" type=\"image\/webp\"><img loading=\"lazy\" src=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/EW_3q.jpg\" alt=\"EW_3q\"   width=\"1000\" height=\"1000\"  decoding=\"async\"  \/><\/picture>        <\/div>\n                              <div class=\"article-images-grid__item\">\n          <picture><source srcset=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/EW_.webp\" type=\"image\/webp\"><img loading=\"lazy\" src=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/EW_.jpg\" alt=\"EW_\"   width=\"1000\" height=\"1000\"  decoding=\"async\"  \/><\/picture>        <\/div>\n            <\/div>\n  \n<h3>Comandi e sistema di guida<\/h3>\n<p>Questa attrezzatura \u00e8 composta da un <strong>sistema di guida con carrello per la movimentazione manuale,<\/strong> con 4 ruote sterzanti e 2 ruote direzionali, che assicura la massima aderenza al terreno e linearit\u00e0 di percorrenza.<\/p>\n  <div class=\"article-product-card single-blog-styles\">\n          <div class=\"article-product-card__image\">\n        <picture><source srcset=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/EW_comandi_2.webp\" type=\"image\/webp\"><img loading=\"lazy\" src=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/EW_comandi_2.jpg\" alt=\"EW_comandi_2\"   width=\"800\" height=\"550\"  decoding=\"async\"  \/><\/picture>      <\/div>\n    \n          <div class=\"article-product-card__text\">\n        <p>Il <strong>sistema di guida, i comandi e il sistema di arresto d\u2019emergenza<\/strong> di Easy Wash 50 <strong>E sono presenti in entrambi i lati,<\/strong> permettendo un controllo dell\u2019impianto in entrambi i sensi di marcia durante la fase di pulizia.<\/p>      <\/div>\n      <\/div>\n  \n<h3>Sistema di lavaggio<\/h3>\n<p>L\u2019impianto di lavaggio \u00e8 composto da una <strong>spazzola inclinabile<\/strong> manualmente in grado di pulire l\u2019intera superficie di camion e autobus<\/p>\n  <div class=\"article-product-card single-blog-styles\">\n          <div class=\"article-product-card__image\">\n        <picture><source srcset=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/EW_collegamento-idrico.webp\" type=\"image\/webp\"><img loading=\"lazy\" src=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/EW_collegamento-idrico.jpg\" alt=\"EW_collegamento-idrico\"   width=\"1000\" height=\"1000\"  decoding=\"async\"  \/><\/picture>      <\/div>\n    \n          <div class=\"article-product-card__text\">\n        <p>Non disponendo di una cisterna, <strong>l\u2019acqua per la detersione dei veicoli \u00e8 fornita da un raccordo esterno all\u2019impianto<\/strong> che va collegato ad un rubinetto.<\/p>      <\/div>\n      <\/div>\n  \n<h3>Installazione e sistema di alimentazione<\/h3>\n<p>L\u2019impianto di lavaggio Easy Wash 50 E <strong>pu\u00f2 essere utilizzato all\u2019interno di un deposito<\/strong> o all\u2019<strong>esterno sul piazzale pavimentato.<\/strong><\/p>\n  <div class=\"article-product-card single-blog-styles\">\n          <div class=\"article-product-card__image\">\n        <picture><source srcset=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/EW_manuale_alimentazione.webp\" type=\"image\/webp\"><img loading=\"lazy\" src=\"https:\/\/itecosrl.com\/wp-content\/uploads\/2026\/05\/EW_manuale_alimentazione.jpg\" alt=\"EW_manuale_alimentazione\"   width=\"800\" height=\"550\"  decoding=\"async\"  \/><\/picture>      <\/div>\n    \n          <div class=\"article-product-card__text\">\n        <p>L\u2019alimentazione dell\u2019impianto avviene attraverso allacciamento diretto con cavo (libero a terra o con linea aerea) ad una presa elettrica.<\/p>      <\/div>\n      <\/div>","protected":false},"excerpt":{"rendered":"<p>Easy Wash 50 E \u00e8 un sistema di lavaggio monospazzola progettato per offrire una pulizia professionale, veloce ed economica per ogni modello di veicolo da trasporto commerciale o pubblico. Comandi e sistema di guida Questa attrezzatura \u00e8 composta da un sistema di guida con carrello per la movimentazione manuale, con 4 ruote sterzanti e 2 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-18588","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"translation":{"provider":"WPGlobus","version":"2.10.10","language":"fr","enabled_languages":["it","en","fr","es"],"languages":{"it":{"title":true,"content":true,"excerpt":false},"en":{"title":true,"content":true,"excerpt":false},"fr":{"title":false,"content":false,"excerpt":false},"es":{"title":false,"content":false,"excerpt":false}}},"acf":[],"_links":{"self":[{"href":"https:\/\/itecosrl.com\/fr\/wp-json\/wp\/v2\/posts\/18588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/itecosrl.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/itecosrl.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/itecosrl.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/itecosrl.com\/fr\/wp-json\/wp\/v2\/comments?post=18588"}],"version-history":[{"count":4,"href":"https:\/\/itecosrl.com\/fr\/wp-json\/wp\/v2\/posts\/18588\/revisions"}],"predecessor-version":[{"id":18603,"href":"https:\/\/itecosrl.com\/fr\/wp-json\/wp\/v2\/posts\/18588\/revisions\/18603"}],"wp:attachment":[{"href":"https:\/\/itecosrl.com\/fr\/wp-json\/wp\/v2\/media?parent=18588"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/itecosrl.com\/fr\/wp-json\/wp\/v2\/categories?post=18588"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/itecosrl.com\/fr\/wp-json\/wp\/v2\/tags?post=18588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}